{"id":15110,"date":"2023-09-13T10:51:23","date_gmt":"2023-09-13T10:51:23","guid":{"rendered":"https:\/\/fasaloula.com\/?page_id=15110"},"modified":"2023-09-18T12:51:53","modified_gmt":"2023-09-18T12:51:53","slug":"%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a","status":"publish","type":"page","link":"https:\/\/fasaloula.com\/en\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/","title":{"rendered":"Exterior design"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1694606107169\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img width=\"1024\" height=\"610\" src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-14-at-09.15.54.jpeg\" class=\"vc_single_image-img attachment-full\" alt=\"\" decoding=\"async\" title=\"WhatsApp Image 2023-09-14 at 09.15.54\" loading=\"lazy\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-14-at-09.15.54.jpeg 1024w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-14-at-09.15.54-768x458.jpeg 768w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-14-at-09.15.54-18x12.jpeg 18w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-14-at-09.15.54-600x357.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1694606118148\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><span class=\"subtitle dash-true style-gray text-right service_details\">Exterior design services<\/span><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1695041295683\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Exterior design services aim to transform outdoor spaces and surroundings into aesthetic and functional environments that suit the needs and desires of clients.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1694605970004\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><span class=\"subtitle dash-true style-dark text-right service_details\">Landscape design<\/span><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1695041361609\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>It includes planning and designing gardens and green spaces and arranging plants, trees and flowers to create a beautiful and balanced landscape.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img width=\"1640\" height=\"924\" src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1-1.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" decoding=\"async\" title=\"1\" loading=\"lazy\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1-1.png 1640w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1-1-1024x577.png 1024w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1-1-768x433.png 768w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1-1-1536x865.png 1536w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1-1-18x10.png 18w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1-1-600x338.png 600w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1694605239163\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img width=\"1024\" height=\"603\" src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-14-at-09.16.01.jpeg\" class=\"vc_single_image-img attachment-full\" alt=\"\" decoding=\"async\" title=\"WhatsApp Image 2023-09-14 at 09.16.01\" loading=\"lazy\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-14-at-09.16.01.jpeg 1024w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-14-at-09.16.01-768x452.jpeg 768w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-14-at-09.16.01-18x12.jpeg 18w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-14-at-09.16.01-600x353.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1694605834063\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><span class=\"subtitle dash-true style-dark text-right service_details\">Interface design<\/span><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1695041373473\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>It includes designing and coordinating the facades of buildings and external facilities to achieve an attractive shape and distinctive identity.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_empty_space\"   style=\"height: 25px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_empty_space\"   style=\"height: 25px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1694605222844\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><span class=\"subtitle dash-true style-dark text-center\">Design of outdoor furniture and fixtures<\/span>\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1695041393598\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>It includes the selection and design of furniture and outdoor elements such as seating, umbrellas, and lighting to provide comfortable and attractive places to sit and enjoy the outdoor climate.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-14139 size-full\" src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/08\/6-4.png\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/08\/6-4.png 940w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/08\/6-4-768x644.png 768w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/08\/6-4-14x12.png 14w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/08\/6-4-600x503.png 600w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey vc_custom_1694606229506  vc_custom_1694606229506\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><span class=\"subtitle dash-true style-dark text-default\">Design of entertainment spaces<\/span><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1694690956262\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"direction: rtl; text-align: center;\">It includes designing spaces for recreational activities such as swimming pools, children's playgrounds and barbecue areas, with an emphasis on safety and fun.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"wpb_gallery wpb_content_element vc_clearfix\" ><div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slides wpb_flexslider flexslider_fade flexslider\" data-interval=\"3\" data-flex_fx=\"fade\"><ul class=\"slides\"><li><a class=\"\" href=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/28-2-1024x577.png\" data-lightbox=\"lightbox[rel-15110-3119612936]\"><img width=\"1640\" height=\"924\" src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/28-2.png\" class=\"attachment-full\" alt=\"\" decoding=\"async\" title=\"28\" loading=\"lazy\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/28-2.png 1640w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/28-2-1024x577.png 1024w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/28-2-768x433.png 768w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/28-2-1536x865.png 1536w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/28-2-18x10.png 18w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/28-2-600x338.png 600w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/a><\/li><li><a class=\"\" href=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/27-2-1024x577.png\" data-lightbox=\"lightbox[rel-15110-3119612936]\"><img width=\"1640\" height=\"924\" src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/27-2.png\" class=\"attachment-full\" alt=\"\" decoding=\"async\" title=\"27\" loading=\"lazy\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/27-2.png 1640w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/27-2-1024x577.png 1024w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/27-2-768x433.png 768w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/27-2-1536x865.png 1536w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/27-2-18x10.png 18w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/27-2-600x338.png 600w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/a><\/li><li><a class=\"\" href=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/26-2-1024x577.png\" data-lightbox=\"lightbox[rel-15110-3119612936]\"><img width=\"1640\" height=\"924\" src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/26-2.png\" class=\"attachment-full\" alt=\"\" decoding=\"async\" title=\"26\" loading=\"lazy\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/26-2.png 1640w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/26-2-1024x577.png 1024w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/26-2-768x433.png 768w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/26-2-1536x865.png 1536w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/26-2-18x10.png 18w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/26-2-600x338.png 600w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/a><\/li><li><a class=\"\" href=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/25-2-1024x577.png\" data-lightbox=\"lightbox[rel-15110-3119612936]\"><img width=\"1640\" height=\"924\" src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/25-2.png\" class=\"attachment-full\" alt=\"\" decoding=\"async\" title=\"25\" loading=\"lazy\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/25-2.png 1640w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/25-2-1024x577.png 1024w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/25-2-768x433.png 768w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/25-2-1536x865.png 1536w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/25-2-18x10.png 18w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/25-2-600x338.png 600w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/a><\/li><li><a class=\"\" href=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/29-2-1024x577.png\" data-lightbox=\"lightbox[rel-15110-3119612936]\"><img width=\"1640\" height=\"924\" src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/29-2.png\" class=\"attachment-full\" alt=\"\" decoding=\"async\" title=\"29\" loading=\"lazy\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/29-2.png 1640w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/29-2-1024x577.png 1024w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/29-2-768x433.png 768w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/29-2-1536x865.png 1536w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/29-2-18x10.png 18w, https:\/\/fasaloula.com\/wp-content\/uploads\/2016\/08\/29-2-600x338.png 600w\" sizes=\"(max-width: 1640px) 100vw, 1640px\" \/><\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1694605406231\"><div class=\"wpb_wrapper\"><span class=\"subtitle dash-true style-dark text-default\">Design of paths and corridors<\/span><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1694605422653\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1695041408113\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>It includes planning and designing beautiful and functional walking paths and walkways within the outdoor areas.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-14976 size-full\" src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2.jpg 2560w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2-1024x683.jpg 1024w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2-768x512.jpg 768w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2-1536x1024.jpg 1536w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2-2048x1366.jpg 2048w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2-18x12.jpg 18w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2-360x240.jpg 360w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2-420x280.jpg 420w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2-480x320.jpg 480w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2-600x400.jpg 600w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/1707-2507-v2-780x520.jpg 780w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"dash style-dark default\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><section class=\"section-gallery gallery-layout-wide grid-fluid captions-default gallery-dark bg-default\"><div class=\"container\"><div class=\"row\"><div class=\"col-md-12\"><div class=\"latest-projects\"><div class=\"gallery-categories normal\"><ul id=\"filters\"><li><a href=\"#\" data-filter=\"*\" class=\"selected\">\u0643\u0644 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639<\/a><\/li><li><a href=\"#\" data-filter=\".63\">\u00a0\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627<\/a><\/li><li><a href=\"#\" data-filter=\".74\">\u0627\u0644\u0646\u0631\u062c\u0633<\/a><\/li><li><a href=\"#\" data-filter=\".69\">\u062d\u064a \u0627\u0644\u0642\u064a\u0631\u0648\u0627\u0646<\/a><\/li><li><a href=\"#\" data-filter=\".73\">\u0639\u0645\u0627\u0631\u0647 \u0633\u0643\u0646\u064a\u0647<\/a><\/li><li><a href=\"#\" data-filter=\".72\">\u0641\u0649 \u0627\u0644\u0631\u064a\u0627\u0636<\/a><\/li><li><a href=\"#\" data-filter=\".68\">\u0641\u0649 \u0627\u0644\u0631\u064a\u0627\u0636 \u0627\u0644\u0645\u0644\u0642\u0627<\/a><\/li><li><a href=\"#\" data-filter=\".67\">\u0641\u0649 \u062d\u0649 \u0627\u0644\u0631\u062d\u0627\u0628<\/a><\/li><li><a href=\"#\" data-filter=\".60\">\u0645\u0631\u062d\u0644\u0647 \u0635\u0628 \u0627\u0644\u0627\u0633\u0627\u0633\u0627\u062a<\/a><\/li><li><a href=\"#\" data-filter=\".71\">\u0645\u0631\u062d\u0644\u0647 \u0635\u0639\u0628 \u0627\u0644\u062e\u0631\u0633\u0627\u0646\u0647<\/a><\/li><\/ul><\/div> <\/div><\/div><\/div><\/div><div id=\"gallery\"><div class=\"container-fluid\"><div class=\"row no-gutter\"><div class=\"col-xs-12 col-sm-6 col-lg-4 item 67\"><a href=\"https:\/\/fasaloula.com\/en\/projects\/%d8%a7%d8%ad%d8%af%d9%89-%d9%85%d8%b4%d8%a7%d8%b1%d9%8a%d8%b9%d9%86%d8%a7-%d9%81%d9%89-%d8%ad%d9%8a-%d8%a7%d9%84%d8%b1%d8%ad%d8%a7%d8%a8\/\" class=\"portfolio-box\"><div class=\"image-container\"><img src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-10.45.26-AM-1-480x320.jpeg\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-10.45.26-AM-1-240x180.jpeg 240w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-10.45.26-AM-1-360x240.jpeg 360w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-10.45.26-AM-1-420x280.jpeg 420w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-10.45.26-AM-1-600x400.jpeg 600w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-10.45.26-AM-1-780x520.jpeg 780w\" width=\"480\" height=\"320\" sizes=\"(min-width: 781px) 600px, calc(100vw - 30px)\" alt=\"\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627 \u0641\u0649 \u062d\u064a \u0627\u0644\u0631\u062d\u0627\u0628\"><\/div><div class=\"portfolio-box-caption\"><div class=\"portfolio-box-caption-content\"><div class=\"project-category text-faded\">\u0641\u0649 \u062d\u0649 \u0627\u0644\u0631\u062d\u0627\u0628<\/div><div class=\"project-name\">\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627 \u0641\u0649 \u062d\u064a \u0627\u0644\u0631\u062d\u0627\u0628<\/div><\/div><\/div><\/a><\/div><div class=\"col-xs-12 col-sm-6 col-lg-4 item 68\"><a href=\"https:\/\/fasaloula.com\/en\/projects\/%d8%a7%d8%ad%d8%af%d9%89-%d9%85%d8%b4%d8%a7%d8%b1%d9%8a%d8%b9%d9%86%d8%a7-%d9%81%d9%89-%d8%a7%d9%84%d8%b1%d9%8a%d8%a7%d8%b6-%d8%a7%d9%84%d9%85%d9%84%d9%82%d8%a7\/\" class=\"portfolio-box\"><div class=\"image-container\"><img src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.27.07-AM-2-1-480x320.jpeg\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.27.07-AM-2-1-240x180.jpeg 240w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.27.07-AM-2-1-360x240.jpeg 360w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.27.07-AM-2-1-420x280.jpeg 420w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.27.07-AM-2-1-600x400.jpeg 600w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.27.07-AM-2-1-780x520.jpeg 780w\" width=\"480\" height=\"320\" sizes=\"(min-width: 781px) 600px, calc(100vw - 30px)\" alt=\"\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627 \u0641\u0649 \u0627\u0644\u0631\u064a\u0627\u0636 \u0627\u0644\u0645\u0644\u0642\u0627\"><\/div><div class=\"portfolio-box-caption\"><div class=\"portfolio-box-caption-content\"><div class=\"project-category text-faded\">\u0641\u0649 \u0627\u0644\u0631\u064a\u0627\u0636 \u0627\u0644\u0645\u0644\u0642\u0627<\/div><div class=\"project-name\">\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627 \u0641\u0649 \u0627\u0644\u0631\u064a\u0627\u0636 \u0627\u0644\u0645\u0644\u0642\u0627<\/div><\/div><\/div><\/a><\/div><div class=\"col-xs-12 col-sm-6 col-lg-4 item 69\"><a href=\"https:\/\/fasaloula.com\/en\/projects\/%d8%a7%d8%ad%d8%af%d9%89-%d9%85%d8%b4%d8%a7%d8%b1%d9%8a%d8%b9%d9%86%d8%a7-%d9%81%d9%89-%d8%a7%d9%84%d8%b1%d9%8a%d8%a7%d8%b6-_%d8%ad%d9%8a-%d8%a7%d9%84%d9%82%d9%8a%d8%b1%d9%88%d8%a7%d9%86\/\" class=\"portfolio-box\"><div class=\"image-container\"><img src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.29.36-AM-480x320.jpeg\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.29.36-AM-240x180.jpeg 240w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.29.36-AM-360x240.jpeg 360w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.29.36-AM-420x280.jpeg 420w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.29.36-AM-600x400.jpeg 600w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.29.36-AM-780x520.jpeg 780w\" width=\"480\" height=\"320\" sizes=\"(min-width: 781px) 600px, calc(100vw - 30px)\" alt=\"\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627 \u0641\u0649 \u0627\u0644\u0631\u064a\u0627\u0636 _\u062d\u064a \u0627\u0644\u0642\u064a\u0631\u0648\u0627\u0646\"><\/div><div class=\"portfolio-box-caption\"><div class=\"portfolio-box-caption-content\"><div class=\"project-category text-faded\">\u062d\u064a \u0627\u0644\u0642\u064a\u0631\u0648\u0627\u0646<\/div><div class=\"project-name\">\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627 \u0641\u0649 \u0627\u0644\u0631\u064a\u0627\u0636 _\u062d\u064a \u0627\u0644\u0642\u064a\u0631\u0648\u0627\u0646<\/div><\/div><\/div><\/a><\/div><div class=\"col-xs-12 col-sm-6 col-lg-4 item 74\"><a href=\"https:\/\/fasaloula.com\/en\/projects\/%d8%a7%d8%ad%d8%af%d9%89-%d9%85%d8%b4%d8%a7%d8%b1%d9%8a%d8%b9%d9%86%d8%a7-%d9%81%d9%89-%d8%a7%d9%84%d8%b1%d9%8a%d8%a7%d8%b6-%d8%a7%d9%84%d9%86%d8%b1%d8%ac%d8%b3\/\" class=\"portfolio-box\"><div class=\"image-container\"><img src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.06.10-AM-1-480x320.jpeg\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.06.10-AM-1-240x180.jpeg 240w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.06.10-AM-1-360x240.jpeg 360w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.06.10-AM-1-420x280.jpeg 420w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.06.10-AM-1-600x400.jpeg 600w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-20-at-11.06.10-AM-1-780x520.jpeg 780w\" width=\"480\" height=\"320\" sizes=\"(min-width: 781px) 600px, calc(100vw - 30px)\" alt=\"\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627 \u0641\u0649 \u0627\u0644\u0631\u064a\u0627\u0636 _ \u0627\u0644\u0646\u0631\u062c\u0633\u00a0\"><\/div><div class=\"portfolio-box-caption\"><div class=\"portfolio-box-caption-content\"><div class=\"project-category text-faded\">\u0627\u0644\u0646\u0631\u062c\u0633<\/div><div class=\"project-name\">\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627 \u0641\u0649 \u0627\u0644\u0631\u064a\u0627\u0636 _ \u0627\u0644\u0646\u0631\u062c\u0633\u00a0<\/div><\/div><\/div><\/a><\/div><div class=\"col-xs-12 col-sm-6 col-lg-4 item 63\"><a href=\"https:\/\/fasaloula.com\/en\/projects\/%d8%a7%d8%ad%d8%af%d9%89-%d9%85%d8%b4%d8%a7%d8%b1%d9%8a%d8%b9%d9%86%d8%a7\/\" class=\"portfolio-box\"><div class=\"image-container\"><img src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.51.32-PM-480x320.jpeg\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.51.32-PM-240x180.jpeg 240w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.51.32-PM-360x240.jpeg 360w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.51.32-PM-420x280.jpeg 420w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.51.32-PM-600x400.jpeg 600w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.51.32-PM-780x520.jpeg 780w\" width=\"480\" height=\"320\" sizes=\"(min-width: 781px) 600px, calc(100vw - 30px)\" alt=\"\u00a0\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627\"><\/div><div class=\"portfolio-box-caption\"><div class=\"portfolio-box-caption-content\"><div class=\"project-category text-faded\">\u00a0\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627<\/div><div class=\"project-name\">\u00a0\u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627<\/div><\/div><\/div><\/a><\/div><div class=\"col-xs-12 col-sm-6 col-lg-4 item 71\"><a href=\"https:\/\/fasaloula.com\/en\/projects\/%d9%85%d8%b1%d8%ad%d9%84%d9%87-%d8%b5%d8%b9%d8%a8-%d8%a7%d9%84%d8%ae%d8%b1%d8%b3%d8%a7%d9%86%d9%87-%d9%81%d9%89-%d8%a7%d8%ad%d8%af%d9%89-%d9%85%d8%b4%d8%a7%d8%b1%d9%8a%d8%b9%d9%86%d8%a7\/\" class=\"portfolio-box\"><div class=\"image-container\"><img src=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.56.23-PM-1-480x320.jpeg\" srcset=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.56.23-PM-1-240x180.jpeg 240w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.56.23-PM-1-360x240.jpeg 360w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.56.23-PM-1-420x280.jpeg 420w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.56.23-PM-1-600x400.jpeg 600w, https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-08-17-at-4.56.23-PM-1-780x520.jpeg 780w\" width=\"480\" height=\"320\" sizes=\"(min-width: 781px) 600px, calc(100vw - 30px)\" alt=\"\u0645\u0631\u062d\u0644\u0647 \u0635\u0639\u0628 \u0627\u0644\u062e\u0631\u0633\u0627\u0646\u0647 \u0641\u0649 \u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627\"><\/div><div class=\"portfolio-box-caption\"><div class=\"portfolio-box-caption-content\"><div class=\"project-category text-faded\">\u0645\u0631\u062d\u0644\u0647 \u0635\u0639\u0628 \u0627\u0644\u062e\u0631\u0633\u0627\u0646\u0647<\/div><div class=\"project-name\">\u0645\u0631\u062d\u0644\u0647 \u0635\u0639\u0628 \u0627\u0644\u062e\u0631\u0633\u0627\u0646\u0647 \u0641\u0649 \u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627<\/div><\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"\u0645\u0631\u062d\u0644\u0647 \u0635\u0639\u0628 \u0627\u0644\u062e\u0631\u0633\u0627\u0646\u0647 \u0641\u0649 \u0627\u062d\u062f\u0649 \u0645\u0634\u0627\u0631\u064a\u0639\u0646\u0627 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u062e\u0627\u0631\u062c\u064a - \u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fasaloula.com\/en\/\u0627\u0644\u062a\u0635\u0645\u064a\u0645-\u0627\u0644\u062e\u0627\u0631\u062c\u064a\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u062e\u0627\u0631\u062c\u064a - \u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fasaloula.com\/en\/\u0627\u0644\u062a\u0635\u0645\u064a\u0645-\u0627\u0644\u062e\u0627\u0631\u062c\u064a\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-18T12:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/08\/6-4.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fasaloula.com\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/\",\"url\":\"https:\/\/fasaloula.com\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/\",\"name\":\"\u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u062e\u0627\u0631\u062c\u064a - \u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621\",\"isPartOf\":{\"@id\":\"https:\/\/fasaloula.com\/#website\"},\"datePublished\":\"2023-09-13T10:51:23+00:00\",\"dateModified\":\"2023-09-18T12:51:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fasaloula.com\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fasaloula.com\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fasaloula.com\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/fasaloula.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u062e\u0627\u0631\u062c\u064a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fasaloula.com\/#website\",\"url\":\"https:\/\/fasaloula.com\/\",\"name\":\"\u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/fasaloula.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fasaloula.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fasaloula.com\/#organization\",\"name\":\"\u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621\",\"url\":\"https:\/\/fasaloula.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fasaloula.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/logo-1.png\",\"contentUrl\":\"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/logo-1.png\",\"width\":200,\"height\":200,\"caption\":\"\u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621\"},\"image\":{\"@id\":\"https:\/\/fasaloula.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u062e\u0627\u0631\u062c\u064a - \u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fasaloula.com\/en\/\u0627\u0644\u062a\u0635\u0645\u064a\u0645-\u0627\u0644\u062e\u0627\u0631\u062c\u064a\/","og_locale":"en_US","og_type":"article","og_title":"\u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u062e\u0627\u0631\u062c\u064a - \u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621","og_url":"https:\/\/fasaloula.com\/en\/\u0627\u0644\u062a\u0635\u0645\u064a\u0645-\u0627\u0644\u062e\u0627\u0631\u062c\u064a\/","og_site_name":"\u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621","article_modified_time":"2023-09-18T12:51:53+00:00","og_image":[{"url":"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/08\/6-4.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fasaloula.com\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/","url":"https:\/\/fasaloula.com\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/","name":"\u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u062e\u0627\u0631\u062c\u064a - \u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621","isPartOf":{"@id":"https:\/\/fasaloula.com\/#website"},"datePublished":"2023-09-13T10:51:23+00:00","dateModified":"2023-09-18T12:51:53+00:00","breadcrumb":{"@id":"https:\/\/fasaloula.com\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fasaloula.com\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fasaloula.com\/%d8%a7%d9%84%d8%aa%d8%b5%d9%85%d9%8a%d9%85-%d8%a7%d9%84%d8%ae%d8%a7%d8%b1%d8%ac%d9%8a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fasaloula.com\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u062e\u0627\u0631\u062c\u064a"}]},{"@type":"WebSite","@id":"https:\/\/fasaloula.com\/#website","url":"https:\/\/fasaloula.com\/","name":"\u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621","description":"","publisher":{"@id":"https:\/\/fasaloula.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fasaloula.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fasaloula.com\/#organization","name":"\u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621","url":"https:\/\/fasaloula.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fasaloula.com\/#\/schema\/logo\/image\/","url":"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/logo-1.png","contentUrl":"https:\/\/fasaloula.com\/wp-content\/uploads\/2023\/09\/logo-1.png","width":200,"height":200,"caption":"\u0634\u0631\u0643\u0629 \u0641\u0627\u0633 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0628\u0646\u0627\u0621"},"image":{"@id":"https:\/\/fasaloula.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fasaloula.com\/en\/wp-json\/wp\/v2\/pages\/15110"}],"collection":[{"href":"https:\/\/fasaloula.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fasaloula.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fasaloula.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fasaloula.com\/en\/wp-json\/wp\/v2\/comments?post=15110"}],"version-history":[{"count":29,"href":"https:\/\/fasaloula.com\/en\/wp-json\/wp\/v2\/pages\/15110\/revisions"}],"predecessor-version":[{"id":15648,"href":"https:\/\/fasaloula.com\/en\/wp-json\/wp\/v2\/pages\/15110\/revisions\/15648"}],"wp:attachment":[{"href":"https:\/\/fasaloula.com\/en\/wp-json\/wp\/v2\/media?parent=15110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}